{"id":5171,"date":"2026-05-15T09:38:19","date_gmt":"2026-05-15T09:38:19","guid":{"rendered":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/?p=5171"},"modified":"2026-05-15T09:38:20","modified_gmt":"2026-05-15T09:38:20","slug":"%f0%9f%8d%84%f0%9f%90%9e-muchomorki-i-biedronki-na-wycieczce-%f0%9f%9a%8d%e2%9c%a8","status":"publish","type":"post","link":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/%f0%9f%8d%84%f0%9f%90%9e-muchomorki-i-biedronki-na-wycieczce-%f0%9f%9a%8d%e2%9c%a8\/","title":{"rendered":"\ud83c\udf44\ud83d\udc1e Muchomorki i Biedronki na wycieczce \ud83d\ude8d\u2728"},"content":{"rendered":"\n<div class=\"wp-block-uagb-advanced-heading uagb-block-422e42ec\"><h3 class=\"uagb-heading-text\">Nasze przedszkolaki z grup <strong>Muchomorki<\/strong> i <strong>Biedronki<\/strong> sp\u0119dzi\u0142y wyj\u0105tkowy dzie\u0144. Dzieci odwiedzi\u0142y <strong>Muzeum Dawnych Rzemios\u0142 w \u017barkach<\/strong>, gdzie pozna\u0142y dawne zawody, narz\u0119dzia oraz ciekawostki zwi\u0105zane z \u017cyciem i prac\u0105 ludzi sprzed lat \ud83d\udee0\ufe0f\ud83c\udffa\u23f3.<br>Nast\u0119pnie uczestniczy\u0142y w kreatywnych <strong>warsztatach kulinarnych w Przystani Le\u015bni\u00f3w<\/strong> \ud83c\udf55\ud83d\udc68\u200d\ud83c\udf73. Przedszkolaki samodzielnie przygotowywa\u0142y pizz\u0119, wybiera\u0142y sk\u0142adniki i \u015bwietnie bawi\u0142y si\u0119 podczas wsp\u00f3lnego gotowania.<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0d69d6be alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0008.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"578\" height=\"1024\" data-id=\"5153\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0008-578x1024.jpg\" alt=\"\" class=\"wp-image-5153\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0008-578x1024.jpg 578w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0008-169x300.jpg 169w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0008-768x1362.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0008-866x1536.jpg 866w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0008.jpg 1155w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0007.jpg\"><img decoding=\"async\" width=\"1024\" height=\"578\" data-id=\"5154\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0007-1024x578.jpg\" alt=\"\" class=\"wp-image-5154\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0007-1024x578.jpg 1024w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0007-300x169.jpg 300w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0007-768x433.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0007-1536x866.jpg 1536w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0007.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0011-578x1024.jpg\"><img decoding=\"async\" width=\"578\" height=\"1024\" data-id=\"5155\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0011-578x1024.jpg\" alt=\"\" class=\"wp-image-5155\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0011-578x1024.jpg 578w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0011-169x300.jpg 169w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0011-768x1362.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0011-866x1536.jpg 866w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0011.jpg 1155w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0012.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"578\" height=\"1024\" data-id=\"5156\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0012-578x1024.jpg\" alt=\"\" class=\"wp-image-5156\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0012-578x1024.jpg 578w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0012-169x300.jpg 169w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0012-768x1362.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0012-866x1536.jpg 866w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0012.jpg 1155w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0009.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"578\" height=\"1024\" data-id=\"5157\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0009-578x1024.jpg\" alt=\"\" class=\"wp-image-5157\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0009-578x1024.jpg 578w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0009-169x300.jpg 169w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0009-768x1362.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0009-866x1536.jpg 866w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0009.jpg 1155w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0021.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"578\" height=\"1024\" data-id=\"5158\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0021-578x1024.jpg\" alt=\"\" class=\"wp-image-5158\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0021-578x1024.jpg 578w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0021-169x300.jpg 169w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0021-768x1362.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0021-866x1536.jpg 866w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0021.jpg 1155w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0022-1024x578.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" data-id=\"5159\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0022-1024x578.jpg\" alt=\"\" class=\"wp-image-5159\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0022-1024x578.jpg 1024w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0022-300x169.jpg 300w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0022-768x433.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0022-1536x866.jpg 1536w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0022.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0023.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"578\" height=\"1024\" data-id=\"5160\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0023-578x1024.jpg\" alt=\"\" class=\"wp-image-5160\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0023-578x1024.jpg 578w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0023-169x300.jpg 169w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0023-768x1362.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0023-866x1536.jpg 866w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0023.jpg 1155w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0017-1024x578.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" data-id=\"5161\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0017-1024x578.jpg\" alt=\"\" class=\"wp-image-5161\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0017-1024x578.jpg 1024w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0017-300x169.jpg 300w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0017-768x433.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0017-1536x866.jpg 1536w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0017.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0010.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" data-id=\"5162\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0010-1024x578.jpg\" alt=\"\" class=\"wp-image-5162\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0010-1024x578.jpg 1024w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0010-300x169.jpg 300w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0010-768x433.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0010-1536x866.jpg 1536w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0010.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0013.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" data-id=\"5163\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0013-1024x578.jpg\" alt=\"\" class=\"wp-image-5163\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0013-1024x578.jpg 1024w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0013-300x169.jpg 300w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0013-768x433.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0013-1536x866.jpg 1536w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0013.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0014.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" data-id=\"5164\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0014-1024x578.jpg\" alt=\"\" class=\"wp-image-5164\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0014-1024x578.jpg 1024w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0014-300x169.jpg 300w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0014-768x433.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0014-1536x866.jpg 1536w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0014.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0015.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" data-id=\"5165\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0015-1024x578.jpg\" alt=\"\" class=\"wp-image-5165\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0015-1024x578.jpg 1024w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0015-300x169.jpg 300w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0015-768x433.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0015-1536x866.jpg 1536w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0015.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0016.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"578\" height=\"1024\" data-id=\"5166\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0016-578x1024.jpg\" alt=\"\" class=\"wp-image-5166\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0016-578x1024.jpg 578w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0016-169x300.jpg 169w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0016-768x1362.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0016-866x1536.jpg 866w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0016.jpg 1155w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0020.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"578\" height=\"1024\" data-id=\"5167\" src=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0020-578x1024.jpg\" alt=\"\" class=\"wp-image-5167\" srcset=\"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0020-578x1024.jpg 578w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0020-169x300.jpg 169w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0020-768x1362.jpg 768w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0020-866x1536.jpg 866w, https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0020.jpg 1155w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/><\/a><\/figure>\n<\/figure>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nasze przedszkolaki z grup Muchomorki i Biedronki sp\u0119dzi\u0142y wyj\u0105tkowy dzie\u0144. Dzieci odwiedzi\u0142y Muzeum Dawnych Rzemios\u0142 w \u017barkach, gdzie pozna\u0142y dawne zawody, narz\u0119dzia oraz ciekawostki zwi\u0105zane z \u017cyciem i prac\u0105 ludzi sprzed lat \ud83d\udee0\ufe0f\ud83c\udffa\u23f3.Nast\u0119pnie uczestniczy\u0142y w kreatywnych warsztatach kulinarnych w Przystani Le\u015bni\u00f3w \ud83c\udf55\ud83d\udc68\u200d\ud83c\udf73. Przedszkolaki samodzielnie przygotowywa\u0142y pizz\u0119, wybiera\u0142y sk\u0142adniki i \u015bwietnie bawi\u0142y si\u0119 podczas wsp\u00f3lnego gotowania.<\/p>\n","protected":false},"author":3,"featured_media":5172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[18],"tags":[],"class_list":["post-5171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"spectra_custom_meta":{"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:1;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:1;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_edit_lock":["1778838140:3"],"_thumbnail_id":["5172"],"_eb_attr":[""],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":[""],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"ast-disable-related-posts":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["set"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_elementor_edit_mode":[""],"_elementor_template_type":[""],"_elementor_data":[""],"_edit_last":["3"],"_eb_reusable_block_ids":["a:0:{}"],"_uag_css_file_name":["uag-css-5171.css"],"_uag_js_file_name":["uag-js-5171.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:56637:\".wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading.uagb-block-422e42ec.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-422e42ec.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-422e42ec.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-422e42ec.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-422e42ec.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-0d69d6be .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0d69d6be .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0d69d6be .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0d69d6be .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0d69d6be .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0d69d6be{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0d69d6be > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1240px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-0d69d6be{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-0d69d6be{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0d69d6be > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-0d69d6be{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-0d69d6be{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0d69d6be > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0d69d6be{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.uagb-block-fe4b9657 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fe4b9657 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-fe4b9657 .uagb-ifb-icon svg{fill: #333;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fe4b9657 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fe4b9657 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fe4b9657 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fe4b9657 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fe4b9657 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fe4b9657 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fe4b9657 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-fe4b9657 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-fe4b9657 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-fe4b9657 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-fe4b9657 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-fe4b9657 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-fe4b9657 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fe4b9657 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-fe4b9657.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-fe4b9657 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fe4b9657.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fe4b9657.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-fe4b9657.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fe4b9657 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fe4b9657 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-fe4b9657 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-fe4b9657 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fe4b9657 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-fe4b9657 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fe4b9657 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fe4b9657 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fe4b9657 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-fe4b9657 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-fe4b9657.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-51ccbdba .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-51ccbdba .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-51ccbdba .uagb-ifb-icon svg{fill: #333;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-51ccbdba .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-51ccbdba .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-51ccbdba .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-51ccbdba .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-51ccbdba .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-51ccbdba .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-51ccbdba .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-51ccbdba .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-51ccbdba .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-51ccbdba .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-51ccbdba .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-51ccbdba .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-51ccbdba .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-51ccbdba .uagb-infobox__content-wrap{text-align: center;}.uagb-block-51ccbdba.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-51ccbdba .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51ccbdba.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-51ccbdba.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-51ccbdba.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-51ccbdba .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-51ccbdba .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-51ccbdba .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-51ccbdba .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-51ccbdba .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-51ccbdba .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-51ccbdba .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-51ccbdba .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-51ccbdba .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-51ccbdba .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-51ccbdba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-3b438839 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3b438839 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-3b438839 .uagb-ifb-icon svg{fill: #333;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3b438839 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3b438839 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3b438839 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3b438839 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3b438839 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3b438839 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-3b438839.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3b438839 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-3b438839 .uagb-ifb-title{margin-bottom: 0px;}.uagb-block-3b438839 .uagb-ifb-desc{font-size: 13px;margin-bottom: 0px;}.uagb-block-3b438839 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-3b438839 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-3b438839 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-3b438839 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3b438839 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-3b438839.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3b438839 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b438839.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b438839.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-3b438839.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-3b438839.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3b438839 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3b438839 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3b438839 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3b438839 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b438839 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3b438839.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3b438839 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b438839 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3b438839 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3b438839 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3b438839 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3b438839.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3b438839.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-bf06c38f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bf06c38f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-bf06c38f .uagb-ifb-icon svg{fill: #333;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bf06c38f .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bf06c38f .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bf06c38f .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bf06c38f .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bf06c38f .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bf06c38f .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bf06c38f .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-bf06c38f .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-bf06c38f .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-bf06c38f .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-bf06c38f .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-bf06c38f .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-bf06c38f .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bf06c38f .uagb-infobox__content-wrap{text-align: center;}.uagb-block-bf06c38f.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bf06c38f .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf06c38f.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bf06c38f.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-bf06c38f.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bf06c38f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bf06c38f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-bf06c38f .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-bf06c38f .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf06c38f .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-bf06c38f .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf06c38f .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bf06c38f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bf06c38f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-bf06c38f .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bf06c38f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.uagb-block-57e62d79.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-57e62d79.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-1de14372.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: rgba(217,147,147,0.53);}.wp-block-uagb-buttons .uagb-block-1de14372 .wp-block-button__link{background: rgba(217,147,147,0.53);}.wp-block-uagb-buttons .uagb-block-1de14372 .wp-block-button__link:hover{background: rgba(217,147,147,0.53);}.wp-block-uagb-buttons .uagb-block-1de14372 .wp-block-button__link:focus{background: rgba(217,147,147,0.53);}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 3px;padding-bottom: 7px;padding-left: 10px;padding-right: 10px;color: #ba0202;margin-top: 0px;margin-bottom: 0px;margin-left: -20px;margin-right: -20px;}.wp-block-uagb-buttons .uagb-block-1de14372 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: #f2e3e3;}.wp-block-uagb-buttons .uagb-block-1de14372 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: #f2e3e3;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: -20px;margin-right: -20px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 30px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 30px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-1de14372.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 30px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 30px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-1de14372.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater .uagb-button__link{color: #ba0202;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater:hover .uagb-button__link{color: #f2e3e3;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater:focus .uagb-button__link{color: #f2e3e3;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #ba0202;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: #f2e3e3;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: #f2e3e3;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.uagb-block-57e62d79.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-57e62d79.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-1de14372.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}@media only screen and (max-width: 767px) {.uagb-block-57e62d79.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-57e62d79.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-1de14372.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-1de14372 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}}\";s:2:\"js\";s:161:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-1de14372' );\n});\n });\";s:18:\"current_block_list\";a:16:{i:0;s:21:\"uagb\/advanced-heading\";i:1;s:14:\"core\/paragraph\";i:2;s:14:\"uagb\/container\";i:3;s:12:\"core\/gallery\";i:4;s:10:\"core\/image\";i:5;s:11:\"core\/search\";i:6;s:10:\"core\/group\";i:7;s:12:\"core\/heading\";i:8;s:17:\"core\/latest-posts\";i:9;s:20:\"core\/latest-comments\";i:10;s:13:\"core\/archives\";i:11;s:15:\"core\/categories\";i:12;s:13:\"uagb\/info-box\";i:13;s:36:\"essential-blocks\/advanced-navigation\";i:14;s:12:\"uagb\/buttons\";i:15;s:18:\"uagb\/buttons-child\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1788334598\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"_elementor_page_assets":["a:0:{}"]},"uagb_featured_image_src":{"full":["https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/897e62b8-4530-42cd-ae80-3fd600b9e323.png",1536,1024,false],"thumbnail":["https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/897e62b8-4530-42cd-ae80-3fd600b9e323-150x150.png",150,150,true],"medium":["https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/897e62b8-4530-42cd-ae80-3fd600b9e323-300x200.png",300,200,true],"medium_large":["https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/897e62b8-4530-42cd-ae80-3fd600b9e323-768x512.png",768,512,true],"large":["https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/897e62b8-4530-42cd-ae80-3fd600b9e323-1024x683.png",1024,683,true],"1536x1536":["https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/897e62b8-4530-42cd-ae80-3fd600b9e323.png",1536,1024,false],"2048x2048":["https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-content\/uploads\/2026\/05\/897e62b8-4530-42cd-ae80-3fd600b9e323.png",1536,1024,false]},"uagb_author_info":{"display_name":"Anna Mlynek","author_link":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/author\/anna\/"},"uagb_comment_info":0,"uagb_excerpt":"Nasze przedszkolaki z grup Muchomorki i Biedronki sp\u0119dzi\u0142y wyj\u0105tkowy dzie\u0144. Dzieci odwiedzi\u0142y Muzeum Dawnych Rzemios\u0142 w \u017barkach, gdzie pozna\u0142y dawne zawody, narz\u0119dzia oraz ciekawostki zwi\u0105zane z \u017cyciem i prac\u0105 ludzi sprzed lat \ud83d\udee0\ufe0f\ud83c\udffa\u23f3.Nast\u0119pnie uczestniczy\u0142y w kreatywnych warsztatach kulinarnych w Przystani Le\u015bni\u00f3w \ud83c\udf55\ud83d\udc68\u200d\ud83c\udf73. Przedszkolaki samodzielnie przygotowywa\u0142y pizz\u0119, wybiera\u0142y sk\u0142adniki i \u015bwietnie bawi\u0142y si\u0119 podczas wsp\u00f3lnego gotowania.","_links":{"self":[{"href":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-json\/wp\/v2\/posts\/5171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-json\/wp\/v2\/comments?post=5171"}],"version-history":[{"count":1,"href":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-json\/wp\/v2\/posts\/5171\/revisions"}],"predecessor-version":[{"id":5173,"href":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-json\/wp\/v2\/posts\/5171\/revisions\/5173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-json\/wp\/v2\/media\/5172"}],"wp:attachment":[{"href":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-json\/wp\/v2\/media?parent=5171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-json\/wp\/v2\/categories?post=5171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zsip1katowice.edu.pl\/przedszkole55\/wp-json\/wp\/v2\/tags?post=5171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}